{"id":1392,"date":"2023-03-10T10:00:00","date_gmt":"2023-03-10T09:00:00","guid":{"rendered":"https:\/\/cfecgc-andra.fr\/?p=1392"},"modified":"2023-03-01T11:10:35","modified_gmt":"2023-03-01T10:10:35","slug":"soutien-aux-abeilles-de-l-a","status":"publish","type":"post","link":"https:\/\/cfecgc-andra.fr\/index.php\/2023\/03\/10\/soutien-aux-abeilles-de-l-a\/","title":{"rendered":"Soutien aux \u00ab\u00a0Abeilles de L.A\u00a0\u00bb !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Soutenues par la f\u00e9d\u00e9ration, nos deux gazelles de Loire-Atlantique, Corinne Liaigre et St\u00e9phanie Thibault\u00a0ont rejoint Nice le 4 mars avant d\u2019affronter une travers\u00e9e de 36 heures pour rejoindre Tanger puis Mekn\u00e8s puis Erfoud. Avant le grand saut, le 9 mars, dans les dunes du d\u00e9sert !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour suivre l\u2019\u00e9quipage 104 du 9 au 16 mars:&nbsp;&nbsp;<a href=\"https:\/\/live2023.rallyeaichadesgazelles.com\/\">https:\/\/live2023.rallyeaichadesgazelles.com<\/a><\/p>\n\n\n\n<h2 class=\"has-vivid-cyan-blue-color has-text-color wp-block-heading\"><strong>Qu&rsquo;est ce que le rallye A\u00efcha des Gazelles ?<\/strong><\/h2>\n\n\n\n<h3 class=\"has-vivid-cyan-blue-color has-text-color wp-block-heading\"><strong>Une aventure incomparable<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Unique en son genre et depuis 1990, il rassemble chaque ann\u00e9e des femmes de 18 \u00e0 71 ans et de nationalit\u00e9s diff\u00e9rentes dans le d\u00e9sert Marocain.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ces femmes que l\u2019on appelle \u00ab les Gazelles \u00bb viennent participer \u00e0 une aventure in\u00e9dite et m\u00e9morable.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sans autre s\u00e9lection que leur d\u00e9termination, quel que soient leur \u00e2ge ou leur milieu, leur nationalit\u00e9 ou leur exp\u00e9rience, les Gazelles viennent vivre une comp\u00e9tition unique :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O\u00f9 les vraies valeurs de tol\u00e9rance, de solidarit\u00e9, de pers\u00e9v\u00e9rance se partagent,<\/li>\n\n\n\n<li>O\u00f9 le respect du pays travers\u00e9 est une priorit\u00e9 gr\u00e2ce aux actions solidaires men\u00e9es<\/li>\n\n\n\n<li>O\u00f9 le respect de l\u2019environnement est assur\u00e9, le Rallye A\u00efcha des Gazelles est le seul rallye-raid au monde \u00e0 \u00eatre certifi\u00e9 norme ISO 14001<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La s\u00e9curit\u00e9 des Gazelles est au c\u0153ur de nos pr\u00e9occupations : gr\u00e2ce \u00e0 une armada humaine (350 organisateurs pour 400 participantes) et technologique, l\u2019organisation assure la g\u00e9olocalisation des \u00e9quipages et d\u00e9ploie ses \u00e9quipes d\u2019assistances\u2026<\/strong><br>Le Rallye A\u00efcha des Gazelles est un retour aux sources de l\u2019aventure mais il est de par son syst\u00e8me, \u00e0 la pointe de la technologie avec une s\u00e9curit\u00e9 assur\u00e9e par satellite.<\/p>\n\n\n\n<h3 class=\"has-vivid-cyan-blue-color has-text-color wp-block-heading\">Une aventure \u00e9co-con\u00e7ue&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis 1990, le rallye d\u00e9veloppe une autre vision de la comp\u00e9tition automobile : un \u00e9co-concept original&nbsp;:&nbsp;<strong>sans&nbsp;<\/strong><strong>vitesse, ou le but de l\u2019aventure est de parcourir le moins de kilom\u00e8tres possible.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sans aucun moyen de navigation \u00e9lectronique, chaque participante est libre de tracer sa propre route en hors-piste<\/strong>&nbsp;pour un retour aux sources de l\u2019Aventure&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les&nbsp;<strong>Gazelles&nbsp;<\/strong>doivent relever chaque jour un d\u00e9fi&nbsp;<strong>sans aucun moyen de communication \u00e9lectronique<\/strong>&nbsp;: analyser la carte avec des coordonn\u00e9es g\u00e9ographiques, appr\u00e9hender les difficult\u00e9s du terrain&nbsp;<strong>et choisir le parcours le plus court possible<\/strong>. Elles doivent effectuer un parcours en pointant des contr\u00f4les de passage&nbsp;<strong>en un minimum de kilom\u00e8tres<\/strong>&nbsp;et non en un minimum de temps. Elles peuvent choisir de contourner la montagne ou de la franchir, de passer par les dunes ou de les \u00e9viter.<\/p>\n\n\n\n<h3 class=\"has-vivid-cyan-blue-color has-text-color wp-block-heading\">Valeurs de femmes, Femmes de valeurs<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le Rallye est un \u00e9v\u00e8nement de valeurs qui&nbsp;<strong>r\u00e9unit des femmes inspirantes depuis plus de 30 ans.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pendant l\u2019aventure, les gazelles doivent se d\u00e9passer, s\u2019entraider, s\u2019adapter, s\u2019ouvrir aux autres\u2026elles partagent entre femmes des valeurs sinc\u00e8res et uniques et une vision commune.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il faut du talent et de la d\u00e9termination pour participer \u00e0 cet \u00e9v\u00e8nement et si vous vous reconnaissez en lisant ces lignes, vous \u00eates pr\u00eates \u00e0 participer \u00e0 l\u2019Aventure&nbsp;!<\/strong><\/p>\n\n\n\n<h3 class=\"has-vivid-cyan-blue-color has-text-color wp-block-heading\">Une aventure responsable et citoyenne<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9ussir depuis 30 ans, c\u2019est avoir fait le choix de la responsabilit\u00e9 dans nos actions !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre organisation est engag\u00e9e dans une d\u00e9marche RSE qui reposent sur 3 piliers :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u2013 L\u2019engagement pour les femmes<\/strong>&nbsp;: Cet \u00e9v\u00e9nement o\u00f9 tout est possible est un r\u00e9v\u00e9lateur de femmes fortes et engag\u00e9es partageant des valeurs communes.<br>Par leur engagement, toutes nos participantes sont des femmes inspirantes \u00e0 fort impact positif !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Le respect de l\u2019environnement<\/strong><br>Nous sommes convaincus qu\u2019il est possible de concilier \u00e9v\u00e9nements sportifs et ma\u00eetrise de ses impacts sur l\u2019environnement.<br>En cr\u00e9ant le Rallye, en 1990, notre organisation cr\u00e9\u00e9e le&nbsp;<strong>concept d\u2019\u00e9co-conduite !<\/strong><br><strong>En 2010, notre d\u00e9marche volontariste se concr\u00e9tise par l\u2019obtention de la norme environnementale ISO 14001. Le Rallye A\u00efcha des Gazelles est la seule comp\u00e9tition automobile au monde ayant cette norme.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Les actions positives citoyennes<\/strong><br><strong>Nous organisons le Rallye avec le coeur !<\/strong><br>Nous sommes fiers de nous impliquer de fa\u00e7on active en faveur de la solidarit\u00e9 en menant des actions positives citoyennes en France et au Maroc.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Soutenues par la f\u00e9d\u00e9ration, nos deux gazelles de Loire-Atlantique, Corinne Liaigre et St\u00e9phanie Thibault\u00a0ont rejoint Nice le 4 mars avant d\u2019affronter une travers\u00e9e de 36 heures pour rejoindre Tanger puis Mekn\u00e8s puis Erfoud. Avant le grand saut, le 9 mars, dans les dunes du d\u00e9sert ! Pour suivre l\u2019\u00e9quipage 104 du 9 au 16 mars:&nbsp;&nbsp;https:\/\/live2023.rallyeaichadesgazelles.com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44,37],"tags":[],"class_list":["post-1392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-confederation-federation","entry","has-media"],"_links":{"self":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts\/1392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1392"}],"version-history":[{"count":4,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts\/1392\/revisions"}],"predecessor-version":[{"id":1398,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts\/1392\/revisions\/1398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/media\/1393"}],"wp:attachment":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}