{"id":1616,"date":"2023-06-08T08:30:37","date_gmt":"2023-06-08T06:30:37","guid":{"rendered":"https:\/\/cfecgc-andra.fr\/?p=1616"},"modified":"2023-06-07T09:23:05","modified_gmt":"2023-06-07T07:23:05","slug":"pourquoi-le-premier-tour-des-elections-professionnels-constitue-un-enjeu-primordial-pour-les-organisations-syndicales","status":"publish","type":"post","link":"https:\/\/cfecgc-andra.fr\/index.php\/2023\/06\/08\/pourquoi-le-premier-tour-des-elections-professionnels-constitue-un-enjeu-primordial-pour-les-organisations-syndicales\/","title":{"rendered":"Pourquoi le premier tour des \u00e9lections professionnels constitue un enjeu primordial pour les organisations syndicales ?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quel que soit le taux de participation \u00e0 ce premier tour, et quel que soit le nombre total d\u2019\u00e9lus qu\u2019elle obtiendra \u00e0 l\u2019issue du second tour, ce sont les r\u00e9sultats du 1er tour au CSE (et non pas au comit\u00e9 national) qui d\u00e9terminent la REPRESENTATIVITE de chaque organisation syndicale pour les 3 ann\u00e9es suivantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si une OS r\u00e9unit moins de 10 % de suffrages, elle sera d\u00e9clar\u00e9e \u00ab non repr\u00e9sentative \u00bb et ne pourra pas participer aux n\u00e9gociations qui interviendront durant les 3 ann\u00e9es \u00e0 venir ; autrement dit, elle n\u2019a plus son mot \u00e0 dire (cas peu vraisemblable \u00e0 l&rsquo;Andra).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, pour \u00eatre d\u00e9l\u00e9gu\u00e9 syndical, un salari\u00e9 doit avoir regroup\u00e9 au moins 10% des suffrages sur son nom propre (ce qui n&rsquo;implique pas n\u00e9cessairement qu&rsquo;il soit \u00e9lu) <br>Si son score est au moins \u00e9gal \u00e0 10 %, celui-ci d\u00e9termine le poids de sa signature durant toutes les n\u00e9gociations futures : c\u2019est important car, depuis une r\u00e9forme de 2017, un accord collectif ne peut \u00eatre valide que s\u2019il est majoritaire, c\u2019est-\u00e0-dire sign\u00e9 par plusieurs OS dont la repr\u00e9sentativit\u00e9 totale est au moins \u00e9gale \u00e0 50 %.<br>Par cons\u00e9quent :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Soit une OS r\u00e9unit \u00e0 elle-seule 50 % des suffrages ou plus, et elle pourra donc, \u00e0 elle-seule, signer avec la direction des accords qui s\u2019appliqueront \u00e0 l\u2019ensemble du personnel ; le cas est rare mais possible : cela s\u2019est produit \u00e0 l\u2019IRSN lors de ses pr\u00e9c\u00e9dentes \u00e9lections professionnelles o\u00f9, contre toute attente et toute logique, c\u2019est un syndicat ouvrier qui, compte tenu de l\u2019abstention massive des ing\u00e9nieurs, cadres et techniciens, a obtenu \u00e0 lui-seul la majorit\u00e9 absolue ;<\/li>\n\n\n\n<li>Soit aucune OS n\u2019a, \u00e0 elle seule cette majorit\u00e9, ce qui est le cas le plus fr\u00e9quent.<\/li>\n\n\n\n<li><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">On voit bien que toute n\u00e9gociation, relative \u00e0 l\u2019une ou l\u2019autre de vos conditions de travail est double : n\u00e9gociation avec la direction, mais \u00e9galement <br>\u00ab alliance \u00bb avec une ou plusieurs autres OS pour parvenir \u00e0 un dispositif acceptable par la majorit\u00e9.<br>A noter enfin, ce qui est loin d\u2019\u00eatre n\u00e9gligeable, que la d\u00e9termination de la repr\u00e9sentativit\u00e9 de chaque OS au niveau f\u00e9d\u00e9ral puis conf\u00e9d\u00e9ral, qui n\u00e9gocieront les accords s\u2019appliquant \u00e0 tous les salari\u00e9s d&rsquo;une branche ou de France est obtenue en faisant la somme des r\u00e9sultats obtenus au seul premier tour des \u00e9lections de chaque CSE d\u2019\u00e9tablissement . L\u2019enjeu est donc non seulement local, mais \u00e9galement national.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, m\u00eame si ce n&rsquo;est pas r\u00e9glementaire, le taux de participation au scrutin est, pour nous, un indicateur de la confiance que vous portez au travail des organisations syndicales et des \u00e9lus dans le dialogue social.  Plus vous votez massivement, meilleur est notre l\u00e9gitimit\u00e9 pour discuter avec la Direction sur des accords qui s&rsquo;appliquent \u00e0 tous. Sur la d\u00e9fense de vos droits individuels comme collectifs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est pourquoi lors des \u00e9lections de septembre, votez. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10 minutes pour voter, 3 ans de retomb\u00e9es<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quel que soit le taux de participation \u00e0 ce premier tour, et quel que soit le nombre total d\u2019\u00e9lus qu\u2019elle obtiendra \u00e0 l\u2019issue du second tour, ce sont les r\u00e9sultats du 1er tour au CSE (et non pas au comit\u00e9 national) qui d\u00e9terminent la REPRESENTATIVITE de chaque organisation syndicale pour les 3 ann\u00e9es suivantes. Si [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe","entry","has-media"],"_links":{"self":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts\/1616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1616"}],"version-history":[{"count":1,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts\/1616\/revisions"}],"predecessor-version":[{"id":1618,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts\/1616\/revisions\/1618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/media\/1617"}],"wp:attachment":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}