{"id":614,"date":"2018-02-14T08:38:26","date_gmt":"2018-02-14T07:38:26","guid":{"rendered":"http:\/\/wordpress.andra.fr\/cfe-cgc\/?p=614"},"modified":"2018-02-14T08:38:26","modified_gmt":"2018-02-14T07:38:26","slug":"negociations-salariales","status":"publish","type":"post","link":"https:\/\/cfecgc-andra.fr\/index.php\/2018\/02\/14\/negociations-salariales\/","title":{"rendered":"N\u00e9gociations salariales"},"content":{"rendered":"<p>Bonjour<\/p>\n<p>aujourd&rsquo;hui (14heure) d\u00e9butent les n\u00e9gociations salariales pour l&rsquo;ann\u00e9e 2018.<\/p>\n<p>&nbsp;<\/p>\n<p>L&rsquo;Andra n&rsquo;avait pas encore connaissance du\u00a0cadrage de la CCIASP il y a quelques jours,\u00a0et \u00a0cette r\u00e9union servira \u00e0 faire le point des mesures de l&rsquo;ann\u00e9e derni\u00e8re par rapport aux\u00a0accords sign\u00e9s.<\/p>\n<p>N&rsquo;h\u00e9sitez pas \u00e0 nous faire parvenir votre vision concernant ce syst\u00e8me\u00a0d&rsquo;augmentation :<\/p>\n<p>augmentations g\u00e9n\u00e9rales et augmentations individuelles<\/p>\n<p>\u00e9galit\u00e9 Homme \/ Femme<\/p>\n<p>Syst\u00e8me d&rsquo;appr\u00e9ciation des collaborateurs&#8230;<\/p>\n<p>Merci de transmette vos remarques, voire d&rsquo;en d\u00e9battre, avec<\/p>\n<p>&nbsp;<\/p>\n<p>Yvon BERTHIER 3306<\/p>\n<p>Yannick ARIMONE 8241<\/p>\n<p>Michel HAYET 6979<\/p>\n<p>Pierre MAULER\u00a0 8096<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour aujourd&rsquo;hui (14heure) d\u00e9butent les n\u00e9gociations salariales pour l&rsquo;ann\u00e9e 2018. &nbsp; L&rsquo;Andra n&rsquo;avait pas encore connaissance du\u00a0cadrage de la CCIASP il y a quelques jours,\u00a0et \u00a0cette r\u00e9union servira \u00e0 faire le point des mesures de l&rsquo;ann\u00e9e derni\u00e8re par rapport aux\u00a0accords sign\u00e9s. N&rsquo;h\u00e9sitez pas \u00e0 nous faire parvenir votre vision concernant ce syst\u00e8me\u00a0d&rsquo;augmentation : augmentations g\u00e9n\u00e9rales [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-614","post","type-post","status-publish","format-standard","hentry","category-non-classe","entry"],"_links":{"self":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts\/614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/comments?post=614"}],"version-history":[{"count":0,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts\/614\/revisions"}],"wp:attachment":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/media?parent=614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/categories?post=614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/tags?post=614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}