{"id":638,"date":"2018-05-18T14:27:59","date_gmt":"2018-05-18T13:27:59","guid":{"rendered":"http:\/\/wordpress.andra.fr\/cfe-cgc\/?p=638"},"modified":"2018-05-18T14:27:59","modified_gmt":"2018-05-18T13:27:59","slug":"ordonnances-macron-et-si-vous-vous-engagiez-maintenant","status":"publish","type":"post","link":"https:\/\/cfecgc-andra.fr\/index.php\/2018\/05\/18\/ordonnances-macron-et-si-vous-vous-engagiez-maintenant\/","title":{"rendered":"ORDONNANCES MACRON : ET SI VOUS VOUS ENGAGIEZ MAINTENANT"},"content":{"rendered":"<p>Vous en entendez parler fr\u00e9quemment, mais en fait le sujet est si vaste et si complexe qu\u2019\u00e0 moins d\u2019\u00eatre f\u00e9ru de droit du travail, vous ne vous \u00eates jamais plong\u00e9 dedans : les Ordonnances Macron.<br \/>\nPourtant ces ordonnances vont profond\u00e9ment modifier le cadre juridique de votre travail. Il est important de vous en pr\u00e9occuper aujourd\u2019hui, au moment o\u00f9 se n\u00e9gocie l\u2019accord de mise en place du CSE au sein de notre Agence.<br \/>\nAu moment o\u00f9 nos projets pourraient r\u00e9v\u00e9ler des signes de fragilit\u00e9, il faut renforcer les modalit\u00e9s de dialogue entre syndicats et direction pour maintenir le consensus qui pr\u00e9vaut \u00e0 l\u2019Andra.<\/p>\n<p><em><strong>Une r\u00e9forme majeure du droit du travail<\/strong><\/em><br \/>\nLes ordonnances Macron s\u2019inscrivent dans un cadre initi\u00e9 depuis plus d\u2019une dizaine d\u2019ann\u00e9es qui consiste \u00e0 assouplir des r\u00e8gles du droit du travail, qui devenaient \u00e0 terme des freins pour le d\u00e9veloppement des entreprises. Ce droit devenait p\u00e9nalisant pour certaines entreprises face \u00e0 la concurrence internationale.<br \/>\nAutant on peut se r\u00e9jouir de voir le pays se r\u00e9former pour se d\u00e9velopper, autant il faut veiller \u00e0 ne pas fragiliser les \u00e9quilibres sociaux qui ont fait aussi la force des entreprises.<br \/>\nAinsi, les aspects protecteurs du droit du travail, des accords de branche (pour nous \u00ab convention de la m\u00e9tallurgie \u00bb), et m\u00eame de votre contrat de travail <strong>pourront \u00eatre remis en cause par des accords n\u00e9goci\u00e9s au sein de l\u2019entreprise<\/strong> tels que les accords de dialogue social encadrant le fonctionnement du CSE puis les consultations r\u00e9currentes (orientations strat\u00e9giques\u2026) et au-del\u00e0, des accords de comp\u00e9titivit\u00e9-emploi.<br \/>\nPar ailleurs, ces r\u00e9formes risquent d\u2019affaiblir le r\u00f4le des repr\u00e9sentants du personnel et des moyens dont ils disposent pour n\u00e9gocier les futurs accords.<br \/>\nC\u2019est face \u00e0 des risques de marginalisation que les syndicats doivent imp\u00e9rativement se renforcer dans les entreprises pour ne pas que les salari\u00e9s se trouvent contraints \u00e0 accepter des remises en cause de leurs conditions de travail et de r\u00e9mun\u00e9ration.<\/p>\n<p><em><strong>Se pr\u00e9parer pour les \u00e9volutions des projets et activit\u00e9s de l\u2019Agence<\/strong><\/em><br \/>\nL\u2019Agence a \u00e9t\u00e9 port\u00e9e depuis pr\u00e8s de trente ans par des projets majeurs qui ont rythm\u00e9 son d\u00e9veloppement : le Centre de l\u2019Aube, le Laboratoire Souterrain et maintenant Cig\u00e9o.<br \/>\nSi les deux premiers sont arriv\u00e9s au stade de la maturit\u00e9, le projet Cig\u00e9o se trouve dans une p\u00e9riode d\u2019interrogations. On voit le cadre juridique et r\u00e9glementaire se complexifier ; la d\u00e9finition technique de l\u2019objet Cig\u00e9o et sa phase pilote sont r\u00e9guli\u00e8rement remises en cause par des injonctions en mati\u00e8res financi\u00e8re ou de s\u00fbret\u00e9 ; on observe l\u2019allongement cons\u00e9cutif des plannings de r\u00e9alisation et les perspectives de d\u00e9marrage des travaux. Last but not least, le nouvel Administrateur G\u00e9n\u00e9ral du CEA, qu\u2019on ne peut soup\u00e7onner de ne pas conna\u00eetre le sujet, a estim\u00e9 devant une commission s\u00e9natoriale qu\u2019en terme de d\u00e9ploiement industriel il n\u2019y a pas d\u2019urgence \u2026<br \/>\nLa perspective d\u2019\u00eatre amen\u00e9 \u00e0 n\u00e9gocier dans les prochaines ann\u00e9es des accords difficiles pour<strong> l\u2019emploi, la formation, les r\u00e9mun\u00e9rations, les primes, la mobilit\u00e9 et les contrats de chantier,<\/strong> n\u2019est donc pas un fantasme ni une perspective absurde.<\/p>\n<p>C\u2019est pour cela que nous devons \u00eatre plus nombreux et donc plus forts dans notre instance syndicale pour pr\u00e9parer les \u00e9volutions de tous ordres qui se profilent afin de pouvoir d\u00e9fendre les int\u00e9r\u00eats des salari\u00e9s, collectivement et individuellement.<\/p>\n<p style=\"text-align: center\"><strong><em>\u00a0R<\/em><\/strong><strong><em>ejoignez la CFE-CGC de l\u2019Andra\u00a0!<\/em><\/strong><\/p>\n<p style=\"text-align: center\"><strong><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Adh\u00e9rez\u00a0!<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous en entendez parler fr\u00e9quemment, mais en fait le sujet est si vaste et si complexe qu\u2019\u00e0 moins d\u2019\u00eatre f\u00e9ru de droit du travail, vous ne vous \u00eates jamais plong\u00e9 dedans : les Ordonnances Macron. Pourtant ces ordonnances vont profond\u00e9ment modifier le cadre juridique de votre travail. Il est important de vous en pr\u00e9occuper aujourd\u2019hui, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-638","post","type-post","status-publish","format-standard","hentry","category-non-classe","entry"],"_links":{"self":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts\/638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/comments?post=638"}],"version-history":[{"count":0,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/posts\/638\/revisions"}],"wp:attachment":[{"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/media?parent=638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/categories?post=638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfecgc-andra.fr\/index.php\/wp-json\/wp\/v2\/tags?post=638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}